{"id":4562,"date":"2019-07-03T05:18:05","date_gmt":"2019-07-03T05:18:05","guid":{"rendered":"https:\/\/fr.isra.land\/?p=4562"},"modified":"2019-07-03T05:18:05","modified_gmt":"2019-07-03T05:18:05","slug":"uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv","status":"publish","type":"post","link":"https:\/\/isra.land\/fr\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\/","title":{"rendered":"Uniquement pour les c\u00e9libataires et les couples sans enfants: Loterie de 50 appartements \u00e0 louer sur Tel Aviv"},"content":{"rendered":"<p style=\"text-align: justify;\">La superbe loterie de 50 appartements \u00e0 louer sur Tel Aviv r\u00e9serv\u00e9e aux c\u00e9libataires ou des couples sans enfants:<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"alignright wp-image-4563 size-medium\" src=\"https:\/\/isra.land\/wp-content\/uploads\/2019\/07\/2154-300x163.jpg\" alt=\"Loterie : 50 appartements \u00e0 louer \u00e0 prix reduit sur Tel Aviv\" width=\"300\" height=\"163\" srcset=\"https:\/\/isra.land\/wp-content\/uploads\/2019\/07\/2154-300x163.jpg 300w, https:\/\/isra.land\/wp-content\/uploads\/2019\/07\/2154-584x320.jpg 584w, https:\/\/isra.land\/wp-content\/uploads\/2019\/07\/2154-496x269.jpg 496w, https:\/\/isra.land\/wp-content\/uploads\/2019\/07\/2154.jpg 590w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h4 style=\"text-align: center;\"><em><strong>Lire aussi :\u00a0<a href=\"https:\/\/fr.isra.land\/opportunite-leuro-se-renforce-face-au-shekel\/\">Opportunit\u00e9 \u2013 L\u2019euro se renforce face au Shekel<\/a><\/strong><\/em><\/h4>\n<p style=\"text-align: justify;\">Ces appartements en location pour les b\u00e9n\u00e9ficiaires auront des loyers d\u2019environ 4 500 NIS par mois. Soit des de deux pi\u00e8ces d\u2019une superficie d\u2019environ 50 m\u00e8tres carr\u00e9s. Avec un contrat d&#8217;une dur\u00e9e de trois ans avec une option pour deux ann\u00e9es suppl\u00e9mentaires.<\/p>\n<h2 style=\"text-align: justify;\">Loterie de 50 appartements \u00e0 louer sur Tel Aviv r\u00e9serv\u00e9e aux c\u00e9libataires ou des couples sans enfants:<\/h2>\n<p style=\"text-align: justify;\">L&#8217;inscription \u00e0 la loterie 50 \u00e0 louer \u00e0 prix r\u00e9duit du projet <a href=\"https:\/\/gindi.com\/\" target=\"_blank\" rel=\"noopener\">TLV Gindi<\/a> \u00e0 Tel-Aviv s&#8217;ouvrira demain (lundi). En outre, l&#8217;inscription restera r\u00e9serv\u00e9e aux les c\u00e9libataires et les couples sans enfants. La municipalit\u00e9 de Tel-Aviv et sa filiale Ezra and Bitzaron, qui en est le bras d\u2019ex\u00e9cution dans le secteur du logement, ont annonc\u00e9 aujourd\u2019hui que l\u2019enregistrement serait ouvert jusqu\u2019au 12 ao\u00fbt.<\/p>\n<h3 style=\"text-align: justify;\">Les crit\u00e8res de d\u00e9termination de l&#8217;admissibilit\u00e9, recommand\u00e9s par le &#8220;comit\u00e9 du logement abordable&#8221; de la ville, comprendra six crit\u00e8res. Notamment:<\/h3>\n<ul>\n<li style=\"text-align: justify;\">ne pas \u00eatre propri\u00e9taire d&#8217;un appartement,<\/li>\n<li style=\"text-align: justify;\">r\u00e9sider \u00e0 Tel Aviv-Jaffa (au moins depuis trois ans ou depuis au moins quatre ans sur les dix derni\u00e8res ann\u00e9es pr\u00e9c\u00e9dant la date d\u00e9terminante),<\/li>\n<li style=\"text-align: justify;\">avoir moins de 45ans,<\/li>\n<li style=\"text-align: justify;\">Repr\u00e9senter un couple sans enfants ou c\u00e9libataire.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">De plus, les candidats doivent \u00e9galement avoir un revenu limit\u00e9 pour pouvoir pr\u00e9tendre \u00e0 l&#8217;inscription<\/p>\n<p style=\"text-align: justify;\">La municipalit\u00e9 de Tel-Aviv a d\u00e9clar\u00e9: &#8220;Contrairement aux tirages pr\u00e9c\u00e9dents, la municipalit\u00e9 de Tel-Aviv-Jaffa a d\u00e9fini la population des c\u00e9libataires et des couples sans enfants comme public cible du projet.<\/p>\n<p style=\"text-align: justify;\">Le maire Ron Huldai a ajout\u00e9: &#8220;Nous sommes la premi\u00e8re autorit\u00e9 isra\u00e9lienne \u00e0 placer la question du co\u00fbt de la vie et du logement au premier rang de ses priorit\u00e9s.&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La superbe loterie de 50 appartements \u00e0 louer sur Tel Aviv r\u00e9serv\u00e9e aux c\u00e9libataires ou des couples sans enfants: Lire aussi :\u00a0Opportunit\u00e9 \u2013 L\u2019euro se renforce face au Shekel Ces appartements en location pour les b\u00e9n\u00e9ficiaires auront des loyers d\u2019environ 4 500 NIS par mois. Soit des de deux pi\u00e8ces d\u2019une superficie d\u2019environ 50 m\u00e8tres [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4565,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uniquement pour les c\u00e9libataires et les couples sans enfants: Loterie de 50 appartements \u00e0 louer sur Tel Aviv - isra.land<\/title>\n<meta name=\"description\" content=\"Uniquement pour les c\u00e9libataires et les couples sans enfants: Loterie de 50 appartements \u00e0 louer sur Tel Aviv. Les appartements Tel Aviviens de deux pi\u00e8ces.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/isra.land\/fr\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uniquement pour les c\u00e9libataires et les couples sans enfants: Loterie de 50 appartements \u00e0 louer sur Tel Aviv - isra.land\" \/>\n<meta property=\"og:description\" content=\"Uniquement pour les c\u00e9libataires et les couples sans enfants: Loterie de 50 appartements \u00e0 louer sur Tel Aviv. Les appartements Tel Aviviens de deux pi\u00e8ces.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/isra.land\/fr\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\/\" \/>\n<meta property=\"og:site_name\" content=\"isra.land\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-03T05:18:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/isra.land\/wp-content\/uploads\/2019\/07\/215454.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"894\" \/>\n\t<meta property=\"og:image:height\" content=\"537\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Israland | In Land we trust\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Israland | In Land we trust\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/isra.land\\\/fr\\\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/isra.land\\\/fr\\\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\\\/\"},\"author\":{\"name\":\"Israland | In Land we trust\",\"@id\":\"https:\\\/\\\/isra.land\\\/#\\\/schema\\\/person\\\/60d1871c2188d72491028e9016521d26\"},\"headline\":\"Uniquement pour les c\u00e9libataires et les couples sans enfants: Loterie de 50 appartements \u00e0 louer sur Tel Aviv\",\"datePublished\":\"2019-07-03T05:18:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/isra.land\\\/fr\\\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\\\/\"},\"wordCount\":345,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/isra.land\\\/fr\\\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/isra.land\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/215454.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/isra.land\\\/fr\\\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/isra.land\\\/fr\\\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\\\/\",\"url\":\"https:\\\/\\\/isra.land\\\/fr\\\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\\\/\",\"name\":\"Uniquement pour les c\u00e9libataires et les couples sans enfants: Loterie de 50 appartements \u00e0 louer sur Tel Aviv - isra.land\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/isra.land\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/isra.land\\\/fr\\\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/isra.land\\\/fr\\\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/isra.land\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/215454.jpg\",\"datePublished\":\"2019-07-03T05:18:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/isra.land\\\/#\\\/schema\\\/person\\\/60d1871c2188d72491028e9016521d26\"},\"description\":\"Uniquement pour les c\u00e9libataires et les couples sans enfants: Loterie de 50 appartements \u00e0 louer sur Tel Aviv. Les appartements Tel Aviviens de deux pi\u00e8ces.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/isra.land\\\/fr\\\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/isra.land\\\/fr\\\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/isra.land\\\/fr\\\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\\\/#primaryimage\",\"url\":\"https:\\\/\\\/isra.land\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/215454.jpg\",\"contentUrl\":\"https:\\\/\\\/isra.land\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/215454.jpg\",\"width\":894,\"height\":537},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/isra.land\\\/fr\\\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/isra.land\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uniquement pour les c\u00e9libataires et les couples sans enfants: Loterie de 50 appartements \u00e0 louer sur Tel Aviv\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/isra.land\\\/#website\",\"url\":\"https:\\\/\\\/isra.land\\\/\",\"name\":\"isra.land\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/isra.land\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/isra.land\\\/#\\\/schema\\\/person\\\/60d1871c2188d72491028e9016521d26\",\"name\":\"Israland | In Land we trust\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d05a0c326a6d49685dadc8d14210f69866cc80be4ea6f50685c80f3570e9cd63?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d05a0c326a6d49685dadc8d14210f69866cc80be4ea6f50685c80f3570e9cd63?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d05a0c326a6d49685dadc8d14210f69866cc80be4ea6f50685c80f3570e9cd63?s=96&d=mm&r=g\",\"caption\":\"Israland | In Land we trust\"},\"sameAs\":[\"https:\\\/\\\/isra.land\"],\"url\":\"https:\\\/\\\/isra.land\\\/fr\\\/author\\\/nwsrln425\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uniquement pour les c\u00e9libataires et les couples sans enfants: Loterie de 50 appartements \u00e0 louer sur Tel Aviv - isra.land","description":"Uniquement pour les c\u00e9libataires et les couples sans enfants: Loterie de 50 appartements \u00e0 louer sur Tel Aviv. Les appartements Tel Aviviens de deux pi\u00e8ces.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/isra.land\/fr\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\/","og_locale":"fr_FR","og_type":"article","og_title":"Uniquement pour les c\u00e9libataires et les couples sans enfants: Loterie de 50 appartements \u00e0 louer sur Tel Aviv - isra.land","og_description":"Uniquement pour les c\u00e9libataires et les couples sans enfants: Loterie de 50 appartements \u00e0 louer sur Tel Aviv. Les appartements Tel Aviviens de deux pi\u00e8ces.","og_url":"https:\/\/isra.land\/fr\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\/","og_site_name":"isra.land","article_published_time":"2019-07-03T05:18:05+00:00","og_image":[{"width":894,"height":537,"url":"https:\/\/isra.land\/wp-content\/uploads\/2019\/07\/215454.jpg","type":"image\/jpeg"}],"author":"Israland | In Land we trust","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Israland | In Land we trust","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/isra.land\/fr\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\/#article","isPartOf":{"@id":"https:\/\/isra.land\/fr\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\/"},"author":{"name":"Israland | In Land we trust","@id":"https:\/\/isra.land\/#\/schema\/person\/60d1871c2188d72491028e9016521d26"},"headline":"Uniquement pour les c\u00e9libataires et les couples sans enfants: Loterie de 50 appartements \u00e0 louer sur Tel Aviv","datePublished":"2019-07-03T05:18:05+00:00","mainEntityOfPage":{"@id":"https:\/\/isra.land\/fr\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\/"},"wordCount":345,"commentCount":0,"image":{"@id":"https:\/\/isra.land\/fr\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\/#primaryimage"},"thumbnailUrl":"https:\/\/isra.land\/wp-content\/uploads\/2019\/07\/215454.jpg","articleSection":["Uncategorized"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/isra.land\/fr\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/isra.land\/fr\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\/","url":"https:\/\/isra.land\/fr\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\/","name":"Uniquement pour les c\u00e9libataires et les couples sans enfants: Loterie de 50 appartements \u00e0 louer sur Tel Aviv - isra.land","isPartOf":{"@id":"https:\/\/isra.land\/#website"},"primaryImageOfPage":{"@id":"https:\/\/isra.land\/fr\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\/#primaryimage"},"image":{"@id":"https:\/\/isra.land\/fr\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\/#primaryimage"},"thumbnailUrl":"https:\/\/isra.land\/wp-content\/uploads\/2019\/07\/215454.jpg","datePublished":"2019-07-03T05:18:05+00:00","author":{"@id":"https:\/\/isra.land\/#\/schema\/person\/60d1871c2188d72491028e9016521d26"},"description":"Uniquement pour les c\u00e9libataires et les couples sans enfants: Loterie de 50 appartements \u00e0 louer sur Tel Aviv. Les appartements Tel Aviviens de deux pi\u00e8ces.","breadcrumb":{"@id":"https:\/\/isra.land\/fr\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/isra.land\/fr\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/isra.land\/fr\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\/#primaryimage","url":"https:\/\/isra.land\/wp-content\/uploads\/2019\/07\/215454.jpg","contentUrl":"https:\/\/isra.land\/wp-content\/uploads\/2019\/07\/215454.jpg","width":894,"height":537},{"@type":"BreadcrumbList","@id":"https:\/\/isra.land\/fr\/uniquement-pour-les-celibataires-et-les-couples-sans-enfants-loterie-de-50-appartements-a-louer-sur-tel-aviv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/isra.land\/fr\/"},{"@type":"ListItem","position":2,"name":"Uniquement pour les c\u00e9libataires et les couples sans enfants: Loterie de 50 appartements \u00e0 louer sur Tel Aviv"}]},{"@type":"WebSite","@id":"https:\/\/isra.land\/#website","url":"https:\/\/isra.land\/","name":"isra.land","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/isra.land\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/isra.land\/#\/schema\/person\/60d1871c2188d72491028e9016521d26","name":"Israland | In Land we trust","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d05a0c326a6d49685dadc8d14210f69866cc80be4ea6f50685c80f3570e9cd63?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d05a0c326a6d49685dadc8d14210f69866cc80be4ea6f50685c80f3570e9cd63?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d05a0c326a6d49685dadc8d14210f69866cc80be4ea6f50685c80f3570e9cd63?s=96&d=mm&r=g","caption":"Israland | In Land we trust"},"sameAs":["https:\/\/isra.land"],"url":"https:\/\/isra.land\/fr\/author\/nwsrln425\/"}]}},"_links":{"self":[{"href":"https:\/\/isra.land\/fr\/wp-json\/wp\/v2\/posts\/4562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/isra.land\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/isra.land\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/isra.land\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/isra.land\/fr\/wp-json\/wp\/v2\/comments?post=4562"}],"version-history":[{"count":0,"href":"https:\/\/isra.land\/fr\/wp-json\/wp\/v2\/posts\/4562\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/isra.land\/fr\/wp-json\/wp\/v2\/media\/4565"}],"wp:attachment":[{"href":"https:\/\/isra.land\/fr\/wp-json\/wp\/v2\/media?parent=4562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/isra.land\/fr\/wp-json\/wp\/v2\/categories?post=4562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/isra.land\/fr\/wp-json\/wp\/v2\/tags?post=4562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}